{"id":45989,"date":"2019-08-29T14:20:36","date_gmt":"2019-08-29T14:20:36","guid":{"rendered":"https:\/\/xn--daocerebral-2db.es\/?p=45989"},"modified":"2024-01-06T14:14:32","modified_gmt":"2024-01-06T14:14:32","slug":"repasamos-la-trayectoria-de-la-udc-de-hermanas-hospitalarias-valencia-con-motivo-del-centenario-del-centro","status":"publish","type":"post","link":"https:\/\/xn--daocerebral-2db.es\/eu\/repasamos-la-trayectoria-de-la-udc-de-hermanas-hospitalarias-valencia-con-motivo-del-centenario-del-centro\/","title":{"rendered":"Repasamos la trayectoria de la UDC de Hermanas Hospitalarias Valencia con motivo del centenario del centro"},"content":{"rendered":"<p>Cumplir cien a\u00f1os de hospitalidad es, principalmente, una ocasi\u00f3n para celebrar y para agradecer, pero tambi\u00e9n para recordar la evoluci\u00f3n durante ese tiempo. El Centro Sociosanitario Nuestra Se\u00f1ora del Carmen ha cumplido un siglo este verano, su Unidad de Da\u00f1o Cerebral, 17 a\u00f1os.<\/p>\n<h5><span style=\"color: #666e74;\">La Red Menni de Da\u00f1o Cerebral\u00a0inici\u00f3 su andadura hace 27 a\u00f1os y en ella se agrupan los centros de las Hermanas Hospitalarias que se dedican a la rehabilitaci\u00f3n de las personas que han sufrido una lesi\u00f3n cerebral. Los centros de la <a href=\"https:\/\/xn--daocerebral-2db.es\/la-red-menni\/\" target=\"_blank\" rel=\"noopener\">Red Menni<\/a> son el resultado de la combinaci\u00f3n de tradici\u00f3n de servicio al paciente con impulso innovador en la asistencia. En 2002, el <a href=\"http:\/\/www.sociosanitarioelcarmen.org\/opencms\/opencms\" target=\"_blank\" rel=\"noopener\">Centro Sociosanitario Ntra. Sra. del Carmen de Valencia<\/a> se uni\u00f3 a la Red con su Unidad de Da\u00f1o Cerebral para personas adultas, posteriormente, en 2008, inaugurar\u00eda la Unidad Ambulatoria de Da\u00f1o Cerebral Infantil y recientemente su Centro de Atenci\u00f3n Temprana de la CIPI (Conselleria de Igualdad Pol\u00edticas Inclusivas).<\/span><\/h5>\n<h4><strong>Or\u00edgenes<\/strong><\/h4>\n<p>El Centro Sociosanitario Nuestra Se\u00f1ora del Carmen fue fundado por do\u00f1a\u00a0<a href=\"https:\/\/es.wikipedia.org\/wiki\/Eugenia_Vi%C3%B1es\" target=\"_blank\" rel=\"noopener\">Eugenia Vi\u00f1es y Cases<\/a>, que dedic\u00f3 sus recursos a actividades caritativas. Su idea inicial era crear un asilo para ni\u00f1as hu\u00e9rfanas pobres, hasta que una hermana hospitalaria, sor Mar\u00eda Delfina, le se\u00f1al\u00f3 que la principal necesidad era la atenci\u00f3n a ni\u00f1as con problemas \u00f3seos derivados de la poliomielitis, y este fue su prop\u00f3sito final.<\/p>\n<p>Tras las pertinentes obras de construcci\u00f3n en un terreno en la playa de la Malvarrosa, la inauguraci\u00f3n del centro se celebr\u00f3 el 16 de julio de 1919. El asilo cont\u00f3 siempre, no solo con las aportaciones de do\u00f1a <strong>Eugenia Vi\u00f1es y Cases<\/strong>, sino tambi\u00e9n con la generosidad y el cari\u00f1o del pueblo de Valencia. Diversos m\u00e9dicos, principalmente especialistas en traumatolog\u00eda, trabajaron voluntariamente en la recuperaci\u00f3n de estas ni\u00f1as consiguiendo un porcentaje notable de curaciones; igualmente se cuidaba la formaci\u00f3n para prep\u00e1rales a integrarse en la sociedad. En pocos a\u00f1os la ocupaci\u00f3n del centro era cercana a las 100 plazas.<\/p>\n<h4><strong>Evoluci\u00f3n<\/strong><\/h4>\n<p>Con el paso de los a\u00f1os y las transformaciones de la sociedad espa\u00f1ola, especialmente en lo que se refiere a la erradicaci\u00f3n de la poliomielitis, el asilo fue modificando su actividad, o mejor dicho su raz\u00f3n de ser. El 1966 comenz\u00f3 a funcionar como centro m\u00e9dico quir\u00fargico, principalmente en la especialidad de traumatolog\u00eda y rehabilitaci\u00f3n, concertado con la Seguridad Social. A pesar de esta transformaci\u00f3n el centro sigui\u00f3 acogiendo a casos de beneficencia cuando la necesidad lo requer\u00eda. No obstante, el a\u00f1o 1974 qued\u00f3 pr\u00e1cticamente sin ni\u00f1as.<\/p>\n<p>En los a\u00f1os posteriores, los adelantos de la medicina exig\u00edan incorporar nuevos servicios y mejorar las condiciones de equipamiento del hospital. 1986 queda marcado en la historia como el a\u00f1o del cambio. En el mes de mayo, el Hospital Nuestra Se\u00f1ora del Carmen ces\u00f3 la actividad quir\u00fargica concertada y se acord\u00f3 con la Conselleria de Trabajo y Seguridad Social la asistencia en r\u00e9gimen de residencia de personas mayores, dada la carencia que hab\u00eda de este servicio.<\/p>\n<p>Con la firma de este convenio con la Generalitat Valenciana se dio un paso importante, siempre siguiendo los criterios para los que fue fundado el centro: ayudar a las personas m\u00e1s necesitadas. Unos a\u00f1os m\u00e1s tarde se inaugura un centro diurno de 35 plazas que vienen a completar el servicio residencial, que cuenta con 115 plazas.<\/p>\n<h4><strong>Rehabilitaci\u00f3n del da\u00f1o cerebral<\/strong><\/h4>\n<p>Con el cambio de siglo, a finales de\u00a0<strong>2002\u00a0<\/strong>se decidi\u00f3 transformar la Unidad de Rehabilitaci\u00f3n Ambulatoria, que continuaba su servicio despu\u00e9s del cierre de la actividad hospitalaria, y<strong>\u00a0se puso en marcha una novedosa y moderna Unidad de Da\u00f1o Cerebral<\/strong>\u00a0para la rehabilitaci\u00f3n de pacientes con graves afecciones tanto f\u00edsicas como psicol\u00f3gicas, originadas por traumatismo craneoencef\u00e1lico, ictus, encefalitis, c\u00e1ncer, accidente cerebrovascular y otras enfermedades. Una unidad\u00a0<strong>en la que se atiende tanto a pacientes privados como a pacientes derivados por la Agencia Valenciana de Salud. De este modo, Valencia se integra en la Red Menni de Da\u00f1o Cerebral que aglutina distintos centros de la Congregaci\u00f3n en Espa\u00f1a.<\/strong><\/p>\n<p><strong>El \u00e1rea Infantil de la Unidad de Da\u00f1o Cerebral se ha convertido desde 2008 en una referencia para el sector en la ciudad de Valencia, hecho <\/strong>que motiv\u00f3 la puesta en marcha en <strong>2012<\/strong>\u00a0de un\u00a0<strong>nuevo Centro de Atenci\u00f3n Temprana\u00a0<\/strong>para dar respuesta a uno de los colectivos m\u00e1s sensibles, como son los\u00a0<strong>ni\u00f1os y ni\u00f1as de 0 a 6 a\u00f1os.<\/strong><\/p>\n<p><a class=\"dt-pswp-item\" href=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Rehabilitacion-danio-cerebral-Valencia-1.jpg\" data-dt-img-description=\"\" data-large_image_width=\"600\" data-large_image_height=\"697\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-79340\" src=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Rehabilitacion-danio-cerebral-Valencia-1.jpg\" alt=\"\" width=\"600\" height=\"697\" srcset=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Rehabilitacion-danio-cerebral-Valencia-1.jpg 600w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Rehabilitacion-danio-cerebral-Valencia-1-258x300.jpg 258w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a>Los datos del \u00faltimo ejercicio se\u00f1alan que fueron 108 las personas adultas atendidas en la Unidad Ambulatoria de DCA, con m\u00e1s de 8.000 sesiones; que 256 ni\u00f1os y ni\u00f1as recibieron atenci\u00f3n en la Unidad Ambulatoria Infantil, donde fueron prestadas 21.357 sesiones y consultas, y que el Centro de Atenci\u00f3n Temprana ha prestado servicio a 47 peques en sus 25 plazas el pasado a\u00f1o.<\/p>\n<h4><strong>Investigaci\u00f3n y docencia <\/strong><\/h4>\n<p>La Unidad de Da\u00f1o cerebral de Hermanas Hospitalarias Valencia, al igual que el resto de los centros de la Red Menni de Da\u00f1o Cerebral, desarrolla una intensa actividad en el \u00e1rea de docencia e investigaci\u00f3n. Cuentan con convenios de colaboraci\u00f3n con universidades que se dedican a la formaci\u00f3n de terapeutas que trabajan en la neurorrehabilitaci\u00f3n y muchos profesionales de la Red mantienen v\u00ednculos con el mundo de la ense\u00f1anza, bien como profesores o como colaboradores docentes. La actividad investigadora se plasma en publicaciones y presentaci\u00f3n de resultados y experiencias en congresos.<\/p>\n<h4><strong>Exposici\u00f3n Fotogr\u00e1fica del Centenario<\/strong><\/h4>\n<p>Con motivo del centenario, a la entrada de la residencia se encuentra una exposici\u00f3n fotogr\u00e1fica a las que pertenecen estas im\u00e1genes. Se trata de una selecci\u00f3n de fotograf\u00edas muy significativas tanto desde el punto de vista hist\u00f3rico como emocional, ya que algunas de las usuarias que aparecen en ellas todav\u00eda siguen en el centro.<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-1 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 33%;\n\t\t\t\t}\n\t\t\t\t#gallery-1 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-1' class='dt-gallery-container gallery galleryid-45989 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href=\"https:\/\/xn--daocerebral-2db.es\/eu\/repasamos-la-trayectoria-de-la-udc-de-hermanas-hospitalarias-valencia-con-motivo-del-centenario-del-centro\/hospitalarias-valencia1-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-45972\" srcset=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia1-150x150.jpg 150w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia1-300x300.jpg 300w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia1-768x768.jpg 768w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia1-1024x1024.jpg 1024w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia1-420x419.jpg 420w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia1.jpg 1200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-45972'>\n\t\t\t\t\tFachada Asilo Ntra. Sra. del Carmen 1919\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href=\"https:\/\/xn--daocerebral-2db.es\/eu\/repasamos-la-trayectoria-de-la-udc-de-hermanas-hospitalarias-valencia-con-motivo-del-centenario-del-centro\/hospitalarias-valencia2-2-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-45976\" srcset=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia2-150x150.jpg 150w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia2-300x300.jpg 300w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia2-768x768.jpg 768w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia2-1024x1024.jpg 1024w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia2-420x419.jpg 420w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia2.jpg 1200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-45976'>\n\t\t\t\t\tNi\u00f1as del Asilo jugando en el jard\u00edn\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href=\"https:\/\/xn--daocerebral-2db.es\/eu\/repasamos-la-trayectoria-de-la-udc-de-hermanas-hospitalarias-valencia-con-motivo-del-centenario-del-centro\/hospitalarias-valencia3-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-45980\" srcset=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia3-150x150.jpg 150w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia3-300x300.jpg 300w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia3-768x768.jpg 768w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia3-1024x1024.jpg 1024w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia3-420x419.jpg 420w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia3.jpg 1200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-45980'>\n\t\t\t\t\tni\u00f1as enfermas sin recursos en camas\n\t\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href=\"https:\/\/xn--daocerebral-2db.es\/eu\/repasamos-la-trayectoria-de-la-udc-de-hermanas-hospitalarias-valencia-con-motivo-del-centenario-del-centro\/hospitalarias-valencia4-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-45984\" srcset=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia4-150x150.jpg 150w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia4-300x300.jpg 300w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia4-768x768.jpg 768w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia4-1024x1024.jpg 1024w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia4-420x419.jpg 420w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia4.jpg 1200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-45984'>\n\t\t\t\t\tTerraza sur, zona de helioterapia\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href=\"https:\/\/xn--daocerebral-2db.es\/eu\/repasamos-la-trayectoria-de-la-udc-de-hermanas-hospitalarias-valencia-con-motivo-del-centenario-del-centro\/hospitalarias-valencia-2-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-45937\" srcset=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia-150x150.jpg 150w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia-300x300.jpg 300w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia-420x419.jpg 420w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Hospitalarias-Valencia.jpg 600w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-45937'>\n\t\t\t\t\tAsiladas de paseo por la playa, significativa imagen de archivo en la Playa de la Malvarrosa\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href=\"https:\/\/xn--daocerebral-2db.es\/eu\/repasamos-la-trayectoria-de-la-udc-de-hermanas-hospitalarias-valencia-con-motivo-del-centenario-del-centro\/eugenia-vinies-i-cases-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Eugenia-Vinies-i-Cases-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-79349\" srcset=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Eugenia-Vinies-i-Cases-150x150.jpg 150w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Eugenia-Vinies-i-Cases-300x300.jpg 300w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Eugenia-Vinies-i-Cases-1024x1024.jpg 1024w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Eugenia-Vinies-i-Cases-768x768.jpg 768w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/08\/Eugenia-Vinies-i-Cases.jpg 1200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-79349'>\n\t\t\t\t\tEugenia Vi\u00f1es i Cases\n\t\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Cumplir cien a\u00f1os de hospitalidad es, principalmente, una ocasi\u00f3n para celebrar y para agradecer, pero tambi\u00e9n para recordar la evoluci\u00f3n durante ese tiempo. El Centro Sociosanitario Nuestra Se\u00f1ora del Carmen ha cumplido un siglo este verano, su Unidad de Da\u00f1o Cerebral, 17 a\u00f1os. <\/p>\n","protected":false},"author":3,"featured_media":45937,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1013,1042,1012,1011],"tags":[2876,1884,1014,1434,1801,2877],"class_list":["post-45989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-eu","category-destacados-eu","category-general-eu","category-noticias-eu","tag-centro-sociosanitario-nuestra-senora-del-carmen-eu","tag-centro-sociosanitario-na-sa-del-carmen-eu","tag-dano-cerebral-eu","tag-hermanas-hospitalarias-valencia-eu","tag-red-menni-eu","tag-rehabiltiacion-eu","category-1013","category-1042","category-1012","category-1011","description-off"],"_links":{"self":[{"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/posts\/45989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/comments?post=45989"}],"version-history":[{"count":8,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/posts\/45989\/revisions"}],"predecessor-version":[{"id":79352,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/posts\/45989\/revisions\/79352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/media\/45937"}],"wp:attachment":[{"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/media?parent=45989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/categories?post=45989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/tags?post=45989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}