{"id":38522,"date":"2018-08-01T11:00:28","date_gmt":"2018-08-01T11:00:27","guid":{"rendered":"http:\/\/xn--daocerebral-2db.es\/?p=38522"},"modified":"2024-01-06T17:28:30","modified_gmt":"2024-01-06T17:28:30","slug":"i-encuentro-de-familias-del-centro-de-dia-de-dano-cerebral-adquirido-de-tenerife","status":"publish","type":"post","link":"https:\/\/xn--daocerebral-2db.es\/eu\/i-encuentro-de-familias-del-centro-de-dia-de-dano-cerebral-adquirido-de-tenerife\/","title":{"rendered":"I Encuentro de Familias del Centro de D\u00eda de Da\u00f1o Cerebral Adquirido de Tenerife"},"content":{"rendered":"<p><a href=\"http:\/\/xn--daocerebral-2db.es\/gestionamos-en-tenerife-el-primer-centro-de-dia-de-dano-cerebral-adquirido-de-canarias\/\" target=\"_blank\" rel=\"noopener\">Tras 7 meses de andadura<\/a>, nuestras familias y personas m\u00e1s allegadas nos han visitado y conocido nuestro espacio diario de trabajo<\/p>\n<p>All\u00e1 por enero, en el Centro de D\u00eda de D\u00eda de Da\u00f1o Cerebral del <a href=\"http:\/\/xn--daocerebral-2db.es\/donde-estamos\/\" target=\"_blank\" rel=\"noopener\">Complejo Acam\u00e1n de Tenerife<\/a> empezaba nuestra actividad y dec\u00edamos algo as\u00ed como <em>&#8220;pasito a pasito&#8221;<\/em>. Sin embargo, el jueves 26 de julio dimos una gran zancada. Por la tarde celebramos el &#8216;<strong>I Encuentro de Familias de personas con Da\u00f1o Cerebral Adquirido&#8217;<\/strong>.<\/p>\n<p>\u00a1C\u00f3mo no!,<strong> fue todo un placer para toda la familia de Hermanas Hospitalarias de Acam\u00e1n y, en especial, para las personas usuarias del Centro de D\u00eda de Da\u00f1o Cerebral Adquirido<\/strong>. Desde el lunes anterior, afront\u00e1bamos la semana con ganas para preparar el acto al detalle. Realizamos una asamblea especial para decidir c\u00f3mo \u00edbamos a preparar nuestro <em>&#8216;piscolabis particular&#8217;<\/em>, con el que siempre recibimos bien a quienes se acercan a conocernos. Acondicionamos espacios, preparamos carteler\u00eda&#8230; Hubo momentos para debates y, aun as\u00ed, nos dio tiempo de realizar nuestro programa diario. \u00bfTodo eso?, pues s\u00ed \u00a1en Acam\u00e1n el tiempo se aprovecha!<\/p>\n<p><a class=\"dt-pswp-item\" href=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2018\/08\/Preparacion-I-Dia-Familias-ACAMAN.jpg\" data-dt-img-description=\"\" data-large_image_width=\"450\" data-large_image_height=\"398\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-80349\" src=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2018\/08\/Preparacion-I-Dia-Familias-ACAMAN.jpg\" alt=\"\" width=\"450\" height=\"398\" srcset=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2018\/08\/Preparacion-I-Dia-Familias-ACAMAN.jpg 450w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2018\/08\/Preparacion-I-Dia-Familias-ACAMAN-300x265.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a>La semana segu\u00eda su curso y ten\u00edamos que salir a comprar al supermercado. El mi\u00e9rcoles, fuimos destino La Laguna a realizar la compra con la que el jueves preparar\u00edamos una peque\u00f1a merienda. Llegamos, colocamos en la cocina todo lo comprado y, sin tomar aire para respirar, nos metimos a afinar la garganta en el Coro que tenemos montado con <strong>Raquel Goz\u00e1lez<\/strong>, la logopeda. S\u00ed, ensayos hubo para dar y regalar, \u00a1y as\u00ed sali\u00f3 de bien!<\/p>\n<p>Ya el jueves, nos pusimos manos a la obra desde bien temprano. S\u00e1ndwich, palomitas, brochetas de frutas, zumos, bizcochones, caf\u00e9s&#8230; fueron algunas de las cosas que acompa\u00f1aron el momento final donde familias, personas usuarias y trabajadores del complejo fuimos uno. Acondicionamos la sala para la ponencia y merienda, \u00a1GRACIAS <a href=\"https:\/\/prezi.com\/itf8e9rf27wr\/presentacion-cad-acaman\/\" target=\"_blank\" rel=\"noopener\">compa\u00f1eros del CAD<\/a>, por los detalles bonitos que nos prepararon para nuestra tarde en familia! Muchas gracias de coraz\u00f3n.<\/p>\n<p>Tras todo el traj\u00edn que ten\u00edamos montado, almorzamos y descansamos, esperando la hora para abrir nuestras puertas a todas esas personas queridas que se acercaron en esta tarde importante para nosotros. Una vez estuvimos todos, <strong>Mariana<\/strong> <strong>Cairos<\/strong>,\u00a0psic\u00f3loga Coordinadora del DCA<strong>,\u00a0<\/strong>dio la bienvenida; seguidamente nuestra compa\u00f1era <strong>Judith<\/strong> expuso sobre qu\u00e9 es el DCA y cu\u00e1les son las secuelas. Tras su extraordinaria exposici\u00f3n, nuestra compa\u00f1era <strong>Tere<\/strong> explic\u00f3 las sesiones individuales y en pareja que realizamos con los distintos profesionales. Y para finalizar, nuestra compa\u00f1era <strong>M\u00f3nica<\/strong> sac\u00f3 todas sus ganas y con una brillante ponencia explic\u00f3 las sesiones grupales, talleres y salidas externas que realizamos.\u00a0Nuestra coordinadora\u00a0cerr\u00f3 la exposici\u00f3n detallando algunos datos relacionados con nuestro centro.<\/p>\n<p>Lleg\u00f3 el momento del coro, ten\u00edamos que actuar y vaya que si lo hicimos, como puede verse en el v\u00eddeo.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/f45clOf65FQ\" width=\"100%\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Y por \u00faltimo no nos pod\u00edamos ir sin antes visualizar la corta, pero gran trayectoria que est\u00e1 familia tiene mediante un audiovisual\u00a0 que reflejaba estos 7 meses al dedillo. \u00a1Se nos hizo corto!<\/p>\n<p>Con el piscolabis culmin\u00f3 esta maravillosa tarde. Las charlas y sonrisas se agolparon en la sala; se dej\u00f3 entrever el buen rollo existente d\u00eda a d\u00eda en esas paredes de la Carretera General de Geneto, 73.<\/p>\n<p>Sin m\u00e1s, desde aqu\u00ed queremos agradecer a todas las personas asistentes y a quienes forman Hermanas Hospitalarias Acam\u00e1n su participaci\u00f3n en este sencillo acto de encuentro. Gracias por venir a esta su casa, siempre ser\u00e1n bien recibidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras 7 meses de andadura, nuestras familias y personas m\u00e1s allegadas nos han visitado y conocido nuestro espacio diario de trabajo All\u00e1 por enero, en el Centro de D\u00eda de D\u00eda de Da\u00f1o Cerebral del Complejo Acam\u00e1n de Tenerife empezaba nuestra actividad y dec\u00edamos algo as\u00ed como &#8220;pasito a pasito&#8221;. Sin embargo, el jueves 26&hellip;<\/p>\n","protected":false},"author":3,"featured_media":80342,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1013,1042,1012],"tags":[2444,1014,1480],"class_list":["post-38522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-eu","category-destacados-eu","category-general-eu","tag-acaman-eu","tag-dano-cerebral-eu","tag-hermanas-hospitalarias-eu","category-1013","category-1042","category-1012","description-off"],"_links":{"self":[{"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/posts\/38522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/comments?post=38522"}],"version-history":[{"count":2,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/posts\/38522\/revisions"}],"predecessor-version":[{"id":80354,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/posts\/38522\/revisions\/80354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/media\/80342"}],"wp:attachment":[{"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/media?parent=38522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/categories?post=38522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/tags?post=38522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}