{"id":15309,"date":"2012-04-13T14:16:03","date_gmt":"2012-04-13T14:16:03","guid":{"rendered":"http:\/\/da\u00f1ocerebral.es\/danio\/\/la-udc-del-hospital-beata-pone-en-marcha-una-sala-de-rehabilitacion-multisensorial-3\/"},"modified":"2017-06-16T11:29:44","modified_gmt":"2017-06-16T11:29:44","slug":"la-udc-del-hospital-beata-pone-en-marcha-una-sala-de-rehabilitacion-multisensorial-3","status":"publish","type":"post","link":"https:\/\/xn--daocerebral-2db.es\/eu\/la-udc-del-hospital-beata-pone-en-marcha-una-sala-de-rehabilitacion-multisensorial-3\/","title":{"rendered":"La UDC del Hospital Beata pone en marcha una sala de rehabilitaci\u00f3n multisensorial"},"content":{"rendered":"<p>&lt;strong&gt;La puesta en marcha de este espacio terap\u00e9utico ha contado con la colaboraci\u00f3n de Obra Social Caja Madrid, el Ministerio de Sanidad, Pol\u00edtica Social e Igualdad y Obra Social Caja Duero.&lt;\/strong&gt;&lt;!&#8211;more&#8211;&gt;<\/p>\n<p>&lt;a href=&#8221;http:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2012\/04\/img_1824.jpg&#8221;&gt;&lt;img class=&#8221; wp-image-4947 alignright&#8221; title=&#8221;Sala multisensorial1&#8243; src=&#8221;http:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2012\/04\/img_1824.jpg&#8221; alt=&#8221;Sala multisensorial1&#8243; width=&#8221;227&#8243; height=&#8221;302&#8243; \/&gt;&lt;\/a&gt;<\/p>\n<p>El pasado 30 de marzo, la Unidad de Da\u00f1o Cerebral del &lt;a title=&#8221;D\u00f3nde estamos&#8221; href=&#8221;http:\/\/xn--daocerebral-2db.es\/donde-estamos\/&#8221;&gt;Hospital Beata Mar\u00eda Ana&lt;\/a&gt; puso en marcha una sala de rehabilitaci\u00f3n multisensorial gracias a la colaboraci\u00f3n de la Obra Social Caja Madrid, el Ministerio de Sanidad, Pol\u00edtica e Igualdad y la Obra Social Caja Duero. Este proyecto ha permitido poner en marcha un espacio terap\u00e9utico donde trabajar de forma integral las alteraciones sensitivas y motoras de nuestros pacientes.<\/p>\n<p>La nueva sala de rehabilitaci\u00f3n multisensorial &lt;strong&gt;proporciona la oportunidad de estimular los sentidos del tacto, o\u00eddo, vista y olfato para facilitar y favorecer la comunicaci\u00f3n del paciente con el entorno y potenciar su autonom\u00eda&lt;\/strong&gt;.<\/p>\n<p>La &lt;strong&gt;sala permite trabajar los est\u00edmulos de una forma independiente o integrada, es decir, el terapeuta puede controlar y ofrecer los est\u00edmulos de forma separada o seleccionar cu\u00e1les\u00a0&lt;\/strong&gt;ofrecer en cada momento, algo que no es posible en una sala convencional. Este es un factor importante puesto que dentro de la lesi\u00f3n cerebral existe una amplia variabilidad de d\u00e9ficits sensoriomotores.\u00a0 En la Unidad contamos con pacientes con alteraciones s\u00f3lo cognitivas (atenci\u00f3n, memoria), o s\u00f3lo conductuales, o s\u00f3lo motoras y con pacientes alteraciones combinadas.<\/p>\n<p>Este tipo de salas se utilizan habitualmente en rehabilitaci\u00f3n infantil, no s\u00f3lo como est\u00edmulo sino tambi\u00e9n como medio de relajaci\u00f3n, sobre todo para ni\u00f1os con par\u00e1lisis cerebral, s\u00edndromes con d\u00e9ficits cognitivos, as\u00ed como en ni\u00f1os con TGD, autismo, etc. y trastornos motores graves. Los ni\u00f1os disfrutan con esta estimulaci\u00f3n lo que ayuda a mejorar su colaboraci\u00f3n en las terapias y contribuye a mejorar su calidad de vida.<\/p>\n<p>La mayor\u00eda de personas que han sufrido un da\u00f1o cerebral presentan un d\u00e9ficit en la habilidad de organizar la informaci\u00f3n para responder adecuadamente a las exigencias del entorno y gracias a esta nueva sala de rehabilitaci\u00f3n multisensorial se van a trabajar los est\u00edmulos para potenciar la comunicaci\u00f3n del usuario con el entorno.<\/p>\n<p>Para m\u00e1s informaci\u00f3n,\u00a0&lt;a title=&#8221;Hospital Beata&#8221; href=&#8221;http:\/\/www.hospitalbeata.org\/opencms\/opencms\/index.html&#8221; target=&#8221;_blank&#8221;&gt;www.&lt;strong&gt;hospitalbeata&lt;\/strong&gt;.org&lt;\/a&gt;<\/p>\n<p>&lt;a href=&#8221;http:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2012\/04\/patrocinios.jpg&#8221;&gt;&lt;img class=&#8221;alignleft wp-image-4946&#8243; title=&#8221;Patrocinios&#8221; src=&#8221;http:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2012\/04\/patrocinios.jpg&#8221; alt=&#8221;Patrocinios&#8221; width=&#8221;557&#8243; height=&#8221;116&#8243; \/&gt;&lt;\/a&gt;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&lt;strong&gt;La puesta en marcha de este espacio terap\u00e9utico ha contado con la colaboraci\u00f3n de Obra Social Caja Madrid, el Ministerio de Sanidad, Pol\u00edtica Social e Igualdad y Obra Social Caja Duero.&lt;\/strong&gt;&lt;!&#8211;more&#8211;&gt; &lt;a href=&#8221;http:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2012\/04\/img_1824.jpg&#8221;&gt;&lt;img class=&#8221; wp-image-4947 alignright&#8221; title=&#8221;Sala multisensorial1&#8243; src=&#8221;http:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2012\/04\/img_1824.jpg&#8221; alt=&#8221;Sala multisensorial1&#8243; width=&#8221;227&#8243; height=&#8221;302&#8243; \/&gt;&lt;\/a&gt; El pasado 30 de marzo, la Unidad de Da\u00f1o Cerebral del&hellip;<\/p>\n","protected":false},"author":3,"featured_media":71032,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1012,1011],"tags":[2124,1015],"class_list":["post-15309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general-eu","category-noticias-eu","tag-autonomia-eu","tag-paralisis-cerebral-eu","category-1012","category-1011","description-off"],"_links":{"self":[{"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/posts\/15309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/comments?post=15309"}],"version-history":[{"count":0,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/posts\/15309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/media\/71032"}],"wp:attachment":[{"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/media?parent=15309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/categories?post=15309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/eu\/wp-json\/wp\/v2\/tags?post=15309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}