{"id":83520,"date":"2009-10-20T11:59:53","date_gmt":"2009-10-20T09:59:53","guid":{"rendered":"https:\/\/xn--daocerebral-2db.es\/es-necesario-garantizar-desde-todos-los-ambitos-una-continuidad-asistencial-efectiva-en-la-atencion-al-dca\/"},"modified":"2024-01-08T09:30:40","modified_gmt":"2024-01-08T09:30:40","slug":"es-necesario-garantizar-desde-todos-los-ambitos-una-continuidad-asistencial-efectiva-en-la-atencion-al-dca","status":"publish","type":"post","link":"https:\/\/xn--daocerebral-2db.es\/en\/es-necesario-garantizar-desde-todos-los-ambitos-una-continuidad-asistencial-efectiva-en-la-atencion-al-dca\/","title":{"rendered":"\u201cEs necesario garantizar desde todos los \u00e1mbitos una continuidad asistencial efectiva en la atenci\u00f3n al DCA\u201d"},"content":{"rendered":"<p><!--:es-->\u201cEl principal reto que tenemos en la atenci\u00f3n del da\u00f1o cerebral adquirido en Espa\u00f1a para los pr\u00f3ximos diez a\u00f1os es consensuar entre todos los actores implicados \u2013Administraci\u00f3n, entidades asistenciales y las personas y familias afectadas- una nueva filosof\u00eda asistencial\u201d. \u00c9ste es el horizonte presentado por <a title=\"Jos\u00e9 Ignacio Quemada\" href=\"http:\/\/xn--daocerebral-2db.es\/tu-equipo-de-tratamiento\/juan-todo\/\" target=\"_blank\" rel=\"noopener\">Jos\u00e9 Ignacio Quemada<\/a>, psiquiatra y director de la Red Menni de Servicios de Da\u00f1o Cerebral, en su intervenci\u00f3n en la \u2018Jornada sobre Atenci\u00f3n al Da\u00f1o Cerebral Adquirido\u2019 que se celebra hoy en el Ministerio de Sanidad y Pol\u00edtica Social.<\/p>\n<p>Quemada ha abogado por que esta \u201cnueva filosof\u00eda asistencial\u201d se base en cuatro pilares fundamentales. El primero de ellos corresponde a \u201cla conveniencia de que se responda a las necesidades de las personas con enfermedades cr\u00f3nicas o discapacidad permanente\u201d, aludiendo as\u00ed al doble perfil, sanitario y sociosanitario de la atenci\u00f3n a estos pacientes.<\/p>\n<p>De igual manera, el experto ha hecho hincapi\u00e9 en la importancia de que la orientaci\u00f3n de la atenci\u00f3n en da\u00f1o cerebral adquirido (DCA) \u201csit\u00fae en el centro del proceso, no s\u00f3lo a la persona con discapacidad, sino tambi\u00e9n a su propia familia\u201d.<\/p>\n<p>Quemada ha proseguido su exposici\u00f3n se\u00f1alando que es necesario un cambio en las unidades b\u00e1sicas de la actividad actual en da\u00f1o cerebral adquirido (episodios en los que \u00e9ste sucede, consultas o intervenciones quir\u00fargicas) \u201cpor procesos de cuidados y de promoci\u00f3n de la autonom\u00eda personal, tal y como recoge la <a href=\"http:\/\/www.boe.es\/aeboe\/consultas\/bases_datos\/doc.php?id=BOE-A-2006-21990\" target=\"_blank\" rel=\"noopener\">Ley 39\/2006 de Promoci\u00f3n de la Autonom\u00eda Personal y Atenci\u00f3n a personas en situaci\u00f3n de dependencia<\/a>\u201d.<\/p>\n<p>\u201cTodo esto -ha indicado- tiene que confluir en un nuevo sistema que garantice la continuidad asistencial de todo el proceso de atenci\u00f3n al paciente con da\u00f1o cerebral adquirido. En este sentido, cit\u00f3 como garant\u00edas de la continuidad asistencial \u201cla correcta identificaci\u00f3n de personas con da\u00f1o cerebral\u201d y la figura del gestor de casos, \u201cque en muchas ocasiones puede coincidir con el papel del trabajador social en el \u00e1mbito sanitario y con el responsable del equipo t\u00e9cnico de apoyo a la persona con da\u00f1o cerebral adquirido y su familia\u201d.<\/p>\n<p><strong>Modelo de atenci\u00f3n a las personas con da\u00f1o cerebral<\/strong><\/p>\n<p>En la jornada, que ha estado organizada por la <a href=\"http:\/\/www.fedace.org\/\" target=\"_blank\" rel=\"noopener\">Federaci\u00f3n Espa\u00f1ola de Da\u00f1o Cerebral (FEDACE)<\/a> en colaboraci\u00f3n con la Agencia de Calidad del Sistema Nacional de Salud y la direcci\u00f3n general de Pol\u00edticas Sectoriales sobre Discapacidad del Ministerio de Sanidad y Pol\u00edtica Social, Quemada ha se\u00f1alado los principios gestores del nuevo paradigma planteado en el documento t\u00e9cnico \u2018<a href=\"http:\/\/xn--daocerebral-2db.es\/forum\/?p=363\">Modelo de Atenci\u00f3n a las Personas con Da\u00f1o Cerebral<\/a>\u2019, editado por el Imserso (Ministerio de Trabajo y Asuntos Sociales) y coordinado por el propio psiquiatra.<\/p>\n<p>As\u00ed, ha enumerado los principios, se\u00f1alando que el nuevo modelo debe velar por la <strong>igualdad de derechos de todos los ciudadanos, establecer una continuidad y coordinaci\u00f3n asistencial<\/strong>, poner el acento en la calidad de vida frente a la curaci\u00f3n, centrarse en la persona y en su familia, funcionar a trav\u00e9s de <strong>equipos multidisciplinares, con programas de atenci\u00f3n individualizados<\/strong>, y que dichos programas se eval\u00faen a trav\u00e9s de criterios de calidad contrastables.<\/p>\n<p>En la elaboraci\u00f3n de este documento t\u00e9cnico participaron expertos de FEDACE \u2013del que Ignacio Quemada es miembro de su comit\u00e9 cient\u00edfico asesor, del Centro de Referencia Estatal de Atenci\u00f3n al Da\u00f1o Cerebral (CEADAC), de la Sociedad Espa\u00f1ola de Rehabilitaci\u00f3n y Medicina F\u00edsica (SERMEF) y del Hospital Aita Menni del Pa\u00eds Vasco.<\/p>\n<p><strong>Variabilidad de los recursos sociales disponibles<\/strong><\/p>\n<p>Tal y como ha expresado Quemada, \u201cactualmente nos vemos inmersos en un proceso en el que las distintas administraciones est\u00e1n adapt\u00e1ndose a un escenario en el que la atenci\u00f3n al da\u00f1o cerebral ha dejado de ser una prestaci\u00f3n graciable, a gozar de una cobertura universal por ley\u201d.<\/p>\n<p>Por ello, ha recomendado durante su intervenci\u00f3n \u201cdesarrollar sistemas de acreditaci\u00f3n y que la Administraci\u00f3n desempe\u00f1e directamente la labor de inspecci\u00f3n y de coordinaci\u00f3n de servicios\u201d.<\/p>\n<p>\u201cEs necesaria la presencia de un equipo t\u00e9cnico de apoyo que est\u00e9 en el centro de la gesti\u00f3n del da\u00f1o cerebral adquirido a trav\u00e9s de los distintos recursos sociales existentes\u201d, entre los que cit\u00f3 \u201clos centros de d\u00eda, los pisos tutelados, las residencias, la ayuda domiciliaria y la teleasistencia, y las pol\u00edticas de empleo, ocupaci\u00f3n y ocio\u201d.<\/p>\n<p><strong>Programas de atenci\u00f3n a familiares<\/strong><\/p>\n<p>El director de la Red Menni de Servicios de Da\u00f1o Cerebral ha comentado igualmente que \u201clas familias que tienen en su seno a una persona con da\u00f1o cerebral adquirido precisan de una informaci\u00f3n, entrenamiento y adaptaci\u00f3n psicol\u00f3gica espec\u00edficas seg\u00fan los momentos del proceso\u201d. As\u00ed, distingui\u00f3 entre \u201cel diagn\u00f3stico y primeras intervenciones, la rehabilitaci\u00f3n y vuelta a casa, y la readaptaci\u00f3n y afrontamiento del futuro\u201d.<!--:--><!--:en-->\u201cEl principal reto que tenemos en la atenci\u00f3n del da\u00f1o cerebral adquirido en Espa\u00f1a para los pr\u00f3ximos diez a\u00f1os es consensuar entre todos los actores implicados \u2013Administraci\u00f3n, entidades asistenciales y las personas y familias afectadas- una nueva filosof\u00eda asistencial\u201d. \u00c9ste es el horizonte presentado por <a href=\"http:\/\/xn--daocerebral-2db.es\/index.php?lang=es&amp;wha=cvs\/nacho.php&amp;dere=2&amp;men=tr\">Jos\u00e9 Ignacio Quemada<\/a>, psiquiatra y director de la Red Menni de Servicios de Da\u00f1o Cerebral, en su intervenci\u00f3n en la \u2018Jornada sobre Atenci\u00f3n al Da\u00f1o Cerebral Adquirido\u2019 que se celebra hoy en el Ministerio de Sanidad y Pol\u00edtica Social.<\/p>\n<p>Quemada ha abogado por que esta \u201cnueva filosof\u00eda asistencial\u201d se base en cuatro pilares fundamentales. El primero de ellos corresponde a \u201cla conveniencia de que se responda a las necesidades de las personas con enfermedades cr\u00f3nicas o discapacidad permanente\u201d, aludiendo as\u00ed al doble perfil, sanitario y sociosanitario de la atenci\u00f3n a estos pacientes.<\/p>\n<p>De igual manera, el experto ha hecho hincapi\u00e9 en la importancia de que la orientaci\u00f3n de la atenci\u00f3n en da\u00f1o cerebral adquirido (DCA) \u201csit\u00fae en el centro del proceso, no s\u00f3lo a la persona con discapacidad, sino tambi\u00e9n a su propia familia\u201d.<\/p>\n<p>Quemada ha proseguido su exposici\u00f3n se\u00f1alando que es necesario un cambio en las unidades b\u00e1sicas de la actividad actual en da\u00f1o cerebral adquirido (episodios en los que \u00e9ste sucede, consultas o intervenciones quir\u00fargicas) \u201cpor procesos de cuidados y de promoci\u00f3n de la autonom\u00eda personal, tal y como recoge la <a href=\"http:\/\/www.boe.es\/aeboe\/consultas\/bases_datos\/doc.php?id=BOE-A-2006-21990\" target=\"_blank\" rel=\"noopener\">Ley 39\/2006 de Promoci\u00f3n de la Autonom\u00eda Personal y Atenci\u00f3n a personas en situaci\u00f3n de dependencia<\/a>\u201d.<\/p>\n<p>\u201cTodo esto -ha indicado- tiene que confluir en un nuevo sistema que garantice la continuidad asistencial de todo el proceso de atenci\u00f3n al paciente con da\u00f1o cerebral adquirido. En este sentido, cit\u00f3 como garant\u00edas de la continuidad asistencial \u201cla correcta identificaci\u00f3n de personas con da\u00f1o cerebral\u201d y la figura del gestor de casos, \u201cque en muchas ocasiones puede coincidir con el papel del trabajador social en el \u00e1mbito sanitario y con el responsable del equipo t\u00e9cnico de apoyo a la persona con da\u00f1o cerebral adquirido y su familia\u201d.<\/p>\n<p><strong>Modelo de atenci\u00f3n a las personas con da\u00f1o cerebral<\/strong><\/p>\n<p>En la jornada, que ha estado organizada por la <a href=\"http:\/\/www.fedace.org\/\" target=\"_blank\" rel=\"noopener\">Federaci\u00f3n Espa\u00f1ola de Da\u00f1o Cerebral (FEDACE)<\/a> en colaboraci\u00f3n con la Agencia de Calidad del Sistema Nacional de Salud y la direcci\u00f3n general de Pol\u00edticas Sectoriales sobre Discapacidad del Ministerio de Sanidad y Pol\u00edtica Social, Quemada ha se\u00f1alado los principios gestores del nuevo paradigma planteado en el documento t\u00e9cnico \u2018<a href=\"http:\/\/xn--daocerebral-2db.es\/forum\/?p=363\">Modelo de Atenci\u00f3n a las Personas con Da\u00f1o Cerebral<\/a>\u2019, editado por el Imserso (Ministerio de Trabajo y Asuntos Sociales) y coordinado por el propio psiquiatra.<\/p>\n<p>As\u00ed, ha enumerado los principios, se\u00f1alando que el nuevo modelo debe velar por la <strong>igualdad de derechos de todos los ciudadanos, establecer una continuidad y coordinaci\u00f3n asistencial<\/strong>, poner el acento en la calidad de vida frente a la curaci\u00f3n, centrarse en la persona y en su familia, funcionar a trav\u00e9s de <strong>equipos multidisciplinares, con programas de atenci\u00f3n individualizados<\/strong>, y que dichos programas se eval\u00faen a trav\u00e9s de criterios de calidad contrastables.<\/p>\n<p>En la elaboraci\u00f3n de este documento t\u00e9cnico participaron expertos de FEDACE \u2013del que Ignacio Quemada es miembro de su comit\u00e9 cient\u00edfico asesor, del Centro de Referencia Estatal de Atenci\u00f3n al Da\u00f1o Cerebral (CEADAC), de la Sociedad Espa\u00f1ola de Rehabilitaci\u00f3n y Medicina F\u00edsica (SERMEF) y del Hospital Aita Menni del Pa\u00eds Vasco.<\/p>\n<p><strong>Variabilidad de los recursos sociales disponibles<\/strong><\/p>\n<p>Tal y como ha expresado Quemada, \u201cactualmente nos vemos inmersos en un proceso en el que las distintas administraciones est\u00e1n adapt\u00e1ndose a un escenario en el que la atenci\u00f3n al da\u00f1o cerebral ha dejado de ser una prestaci\u00f3n graciable, a gozar de una cobertura universal por ley\u201d.<\/p>\n<p>Por ello, ha recomendado durante su intervenci\u00f3n \u201cdesarrollar sistemas de acreditaci\u00f3n y que la Administraci\u00f3n desempe\u00f1e directamente la labor de inspecci\u00f3n y de coordinaci\u00f3n de servicios\u201d.<\/p>\n<p>\u201cEs necesaria la presencia de un equipo t\u00e9cnico de apoyo que est\u00e9 en el centro de la gesti\u00f3n del da\u00f1o cerebral adquirido a trav\u00e9s de los distintos recursos sociales existentes\u201d, entre los que cit\u00f3 \u201clos centros de d\u00eda, los pisos tutelados, las residencias, la ayuda domiciliaria y la teleasistencia, y las pol\u00edticas de empleo, ocupaci\u00f3n y ocio\u201d.<\/p>\n<p><strong>Programas de atenci\u00f3n a familiares<\/strong><\/p>\n<p>El director de la Red Menni de Servicios de Da\u00f1o Cerebral ha comentado igualmente que \u201clas familias que tienen en su seno a una persona con da\u00f1o cerebral adquirido precisan de una informaci\u00f3n, entrenamiento y adaptaci\u00f3n psicol\u00f3gica espec\u00edficas seg\u00fan los momentos del proceso\u201d. As\u00ed, distingui\u00f3 entre \u201cel diagn\u00f3stico y primeras intervenciones, la rehabilitaci\u00f3n y vuelta a casa, y la readaptaci\u00f3n y afrontamiento del futuro\u201d.<!--:--><!--:eu-->\u201cEl principal reto que tenemos en la atenci\u00f3n del da\u00f1o cerebral adquirido en Espa\u00f1a para los pr\u00f3ximos diez a\u00f1os es consensuar entre todos los actores implicados \u2013Administraci\u00f3n, entidades asistenciales y las personas y familias afectadas- una nueva filosof\u00eda asistencial\u201d. \u00c9ste es el horizonte presentado por <a href=\"http:\/\/xn--daocerebral-2db.es\/index.php?lang=es&amp;wha=cvs\/nacho.php&amp;dere=2&amp;men=tr\">Jos\u00e9 Ignacio Quemada<\/a>, psiquiatra y director de la Red Menni de Servicios de Da\u00f1o Cerebral, en su intervenci\u00f3n en la \u2018Jornada sobre Atenci\u00f3n al Da\u00f1o Cerebral Adquirido\u2019 que se celebra hoy en el Ministerio de Sanidad y Pol\u00edtica Social.<\/p>\n<p>Quemada ha abogado por que esta \u201cnueva filosof\u00eda asistencial\u201d se base en cuatro pilares fundamentales. El primero de ellos corresponde a \u201cla conveniencia de que se responda a las necesidades de las personas con enfermedades cr\u00f3nicas o discapacidad permanente\u201d, aludiendo as\u00ed al doble perfil, sanitario y sociosanitario de la atenci\u00f3n a estos pacientes.<\/p>\n<p>De igual manera, el experto ha hecho hincapi\u00e9 en la importancia de que la orientaci\u00f3n de la atenci\u00f3n en da\u00f1o cerebral adquirido (DCA) \u201csit\u00fae en el centro del proceso, no s\u00f3lo a la persona con discapacidad, sino tambi\u00e9n a su propia familia\u201d.<\/p>\n<p>Quemada ha proseguido su exposici\u00f3n se\u00f1alando que es necesario un cambio en las unidades b\u00e1sicas de la actividad actual en da\u00f1o cerebral adquirido (episodios en los que \u00e9ste sucede, consultas o intervenciones quir\u00fargicas) \u201cpor procesos de cuidados y de promoci\u00f3n de la autonom\u00eda personal, tal y como recoge la <a href=\"http:\/\/www.boe.es\/aeboe\/consultas\/bases_datos\/doc.php?id=BOE-A-2006-21990\" target=\"_blank\" rel=\"noopener\">Ley 39\/2006 de Promoci\u00f3n de la Autonom\u00eda Personal y Atenci\u00f3n a personas en situaci\u00f3n de dependencia<\/a>\u201d.<\/p>\n<p>\u201cTodo esto -ha indicado- tiene que confluir en un nuevo sistema que garantice la continuidad asistencial de todo el proceso de atenci\u00f3n al paciente con da\u00f1o cerebral adquirido. En este sentido, cit\u00f3 como garant\u00edas de la continuidad asistencial \u201cla correcta identificaci\u00f3n de personas con da\u00f1o cerebral\u201d y la figura del gestor de casos, \u201cque en muchas ocasiones puede coincidir con el papel del trabajador social en el \u00e1mbito sanitario y con el responsable del equipo t\u00e9cnico de apoyo a la persona con da\u00f1o cerebral adquirido y su familia\u201d.<\/p>\n<p><strong>Modelo de atenci\u00f3n a las personas con da\u00f1o cerebral<\/strong><\/p>\n<p>En la jornada, que ha estado organizada por la <a href=\"http:\/\/www.fedace.org\/\" target=\"_blank\" rel=\"noopener\">Federaci\u00f3n Espa\u00f1ola de Da\u00f1o Cerebral (FEDACE)<\/a> en colaboraci\u00f3n con la Agencia de Calidad del Sistema Nacional de Salud y la direcci\u00f3n general de Pol\u00edticas Sectoriales sobre Discapacidad del Ministerio de Sanidad y Pol\u00edtica Social, Quemada ha se\u00f1alado los principios gestores del nuevo paradigma planteado en el documento t\u00e9cnico \u2018<a href=\"http:\/\/xn--daocerebral-2db.es\/forum\/?p=363\">Modelo de Atenci\u00f3n a las Personas con Da\u00f1o Cerebral<\/a>\u2019, editado por el Imserso (Ministerio de Trabajo y Asuntos Sociales) y coordinado por el propio psiquiatra.<\/p>\n<p>As\u00ed, ha enumerado los principios, se\u00f1alando que el nuevo modelo debe velar por la <strong>igualdad de derechos de todos los ciudadanos, establecer una continuidad y coordinaci\u00f3n asistencial<\/strong>, poner el acento en la calidad de vida frente a la curaci\u00f3n, centrarse en la persona y en su familia, funcionar a trav\u00e9s de <strong>equipos multidisciplinares, con programas de atenci\u00f3n individualizados<\/strong>, y que dichos programas se eval\u00faen a trav\u00e9s de criterios de calidad contrastables.<\/p>\n<p>En la elaboraci\u00f3n de este documento t\u00e9cnico participaron expertos de FEDACE \u2013del que Ignacio Quemada es miembro de su comit\u00e9 cient\u00edfico asesor, del Centro de Referencia Estatal de Atenci\u00f3n al Da\u00f1o Cerebral (CEADAC), de la Sociedad Espa\u00f1ola de Rehabilitaci\u00f3n y Medicina F\u00edsica (SERMEF) y del Hospital Aita Menni del Pa\u00eds Vasco.<\/p>\n<p><strong>Variabilidad de los recursos sociales disponibles<\/strong><\/p>\n<p>Tal y como ha expresado Quemada, \u201cactualmente nos vemos inmersos en un proceso en el que las distintas administraciones est\u00e1n adapt\u00e1ndose a un escenario en el que la atenci\u00f3n al da\u00f1o cerebral ha dejado de ser una prestaci\u00f3n graciable, a gozar de una cobertura universal por ley\u201d.<\/p>\n<p>Por ello, ha recomendado durante su intervenci\u00f3n \u201cdesarrollar sistemas de acreditaci\u00f3n y que la Administraci\u00f3n desempe\u00f1e directamente la labor de inspecci\u00f3n y de coordinaci\u00f3n de servicios\u201d.<\/p>\n<p>\u201cEs necesaria la presencia de un equipo t\u00e9cnico de apoyo que est\u00e9 en el centro de la gesti\u00f3n del da\u00f1o cerebral adquirido a trav\u00e9s de los distintos recursos sociales existentes\u201d, entre los que cit\u00f3 \u201clos centros de d\u00eda, los pisos tutelados, las residencias, la ayuda domiciliaria y la teleasistencia, y las pol\u00edticas de empleo, ocupaci\u00f3n y ocio\u201d.<\/p>\n<p><strong>Programas de atenci\u00f3n a familiares<\/strong><\/p>\n<p>El director de la Red Menni de Servicios de Da\u00f1o Cerebral ha comentado igualmente que \u201clas familias que tienen en su seno a una persona con da\u00f1o cerebral adquirido precisan de una informaci\u00f3n, entrenamiento y adaptaci\u00f3n psicol\u00f3gica espec\u00edficas seg\u00fan los momentos del proceso\u201d. As\u00ed, distingui\u00f3 entre \u201cel diagn\u00f3stico y primeras intervenciones, la rehabilitaci\u00f3n y vuelta a casa, y la readaptaci\u00f3n y afrontamiento del futuro\u201d.<!--:--><!--:ca-->\u201cEl principal reto que tenemos en la atenci\u00f3n del da\u00f1o cerebral adquirido en Espa\u00f1a para los pr\u00f3ximos diez a\u00f1os es consensuar entre todos los actores implicados \u2013Administraci\u00f3n, entidades asistenciales y las personas y familias afectadas- una nueva filosof\u00eda asistencial\u201d. \u00c9ste es el horizonte presentado por <a href=\"http:\/\/xn--daocerebral-2db.es\/index.php?lang=es&amp;wha=cvs\/nacho.php&amp;dere=2&amp;men=tr\">Jos\u00e9 Ignacio Quemada<\/a>, psiquiatra y director de la Red Menni de Servicios de Da\u00f1o Cerebral, en su intervenci\u00f3n en la \u2018Jornada sobre Atenci\u00f3n al Da\u00f1o Cerebral Adquirido\u2019 que se celebra hoy en el Ministerio de Sanidad y Pol\u00edtica Social.<\/p>\n<p>Quemada ha abogado por que esta \u201cnueva filosof\u00eda asistencial\u201d se base en cuatro pilares fundamentales. El primero de ellos corresponde a \u201cla conveniencia de que se responda a las necesidades de las personas con enfermedades cr\u00f3nicas o discapacidad permanente\u201d, aludiendo as\u00ed al doble perfil, sanitario y sociosanitario de la atenci\u00f3n a estos pacientes.<\/p>\n<p>De igual manera, el experto ha hecho hincapi\u00e9 en la importancia de que la orientaci\u00f3n de la atenci\u00f3n en da\u00f1o cerebral adquirido (DCA) \u201csit\u00fae en el centro del proceso, no s\u00f3lo a la persona con discapacidad, sino tambi\u00e9n a su propia familia\u201d.<\/p>\n<p>Quemada ha proseguido su exposici\u00f3n se\u00f1alando que es necesario un cambio en las unidades b\u00e1sicas de la actividad actual en da\u00f1o cerebral adquirido (episodios en los que \u00e9ste sucede, consultas o intervenciones quir\u00fargicas) \u201cpor procesos de cuidados y de promoci\u00f3n de la autonom\u00eda personal, tal y como recoge la <a href=\"http:\/\/www.boe.es\/aeboe\/consultas\/bases_datos\/doc.php?id=BOE-A-2006-21990\" target=\"_blank\" rel=\"noopener\">Ley 39\/2006 de Promoci\u00f3n de la Autonom\u00eda Personal y Atenci\u00f3n a personas en situaci\u00f3n de dependencia<\/a>\u201d.<\/p>\n<p>\u201cTodo esto -ha indicado- tiene que confluir en un nuevo sistema que garantice la continuidad asistencial de todo el proceso de atenci\u00f3n al paciente con da\u00f1o cerebral adquirido. En este sentido, cit\u00f3 como garant\u00edas de la continuidad asistencial \u201cla correcta identificaci\u00f3n de personas con da\u00f1o cerebral\u201d y la figura del gestor de casos, \u201cque en muchas ocasiones puede coincidir con el papel del trabajador social en el \u00e1mbito sanitario y con el responsable del equipo t\u00e9cnico de apoyo a la persona con da\u00f1o cerebral adquirido y su familia\u201d.<\/p>\n<p><strong>Modelo de atenci\u00f3n a las personas con da\u00f1o cerebral<\/strong><\/p>\n<p>En la jornada, que ha estado organizada por la <a href=\"http:\/\/www.fedace.org\/\" target=\"_blank\" rel=\"noopener\">Federaci\u00f3n Espa\u00f1ola de Da\u00f1o Cerebral (FEDACE)<\/a> en colaboraci\u00f3n con la Agencia de Calidad del Sistema Nacional de Salud y la direcci\u00f3n general de Pol\u00edticas Sectoriales sobre Discapacidad del Ministerio de Sanidad y Pol\u00edtica Social, Quemada ha se\u00f1alado los principios gestores del nuevo paradigma planteado en el documento t\u00e9cnico \u2018<a href=\"http:\/\/xn--daocerebral-2db.es\/forum\/?p=363\">Modelo de Atenci\u00f3n a las Personas con Da\u00f1o Cerebral<\/a>\u2019, editado por el Imserso (Ministerio de Trabajo y Asuntos Sociales) y coordinado por el propio psiquiatra.<\/p>\n<p>As\u00ed, ha enumerado los principios, se\u00f1alando que el nuevo modelo debe velar por la <strong>igualdad de derechos de todos los ciudadanos, establecer una continuidad y coordinaci\u00f3n asistencial<\/strong>, poner el acento en la calidad de vida frente a la curaci\u00f3n, centrarse en la persona y en su familia, funcionar a trav\u00e9s de <strong>equipos multidisciplinares, con programas de atenci\u00f3n individualizados<\/strong>, y que dichos programas se eval\u00faen a trav\u00e9s de criterios de calidad contrastables.<\/p>\n<p>En la elaboraci\u00f3n de este documento t\u00e9cnico participaron expertos de FEDACE \u2013del que Ignacio Quemada es miembro de su comit\u00e9 cient\u00edfico asesor, del Centro de Referencia Estatal de Atenci\u00f3n al Da\u00f1o Cerebral (CEADAC), de la Sociedad Espa\u00f1ola de Rehabilitaci\u00f3n y Medicina F\u00edsica (SERMEF) y del Hospital Aita Menni del Pa\u00eds Vasco.<\/p>\n<p><strong>Variabilidad de los recursos sociales disponibles<\/strong><\/p>\n<p>Tal y como ha expresado Quemada, \u201cactualmente nos vemos inmersos en un proceso en el que las distintas administraciones est\u00e1n adapt\u00e1ndose a un escenario en el que la atenci\u00f3n al da\u00f1o cerebral ha dejado de ser una prestaci\u00f3n graciable, a gozar de una cobertura universal por ley\u201d.<\/p>\n<p>Por ello, ha recomendado durante su intervenci\u00f3n \u201cdesarrollar sistemas de acreditaci\u00f3n y que la Administraci\u00f3n desempe\u00f1e directamente la labor de inspecci\u00f3n y de coordinaci\u00f3n de servicios\u201d.<\/p>\n<p>\u201cEs necesaria la presencia de un equipo t\u00e9cnico de apoyo que est\u00e9 en el centro de la gesti\u00f3n del da\u00f1o cerebral adquirido a trav\u00e9s de los distintos recursos sociales existentes\u201d, entre los que cit\u00f3 \u201clos centros de d\u00eda, los pisos tutelados, las residencias, la ayuda domiciliaria y la teleasistencia, y las pol\u00edticas de empleo, ocupaci\u00f3n y ocio\u201d.<\/p>\n<p><strong>Programas de atenci\u00f3n a familiares<\/strong><\/p>\n<p>El director de la Red Menni de Servicios de Da\u00f1o Cerebral ha comentado igualmente que \u201clas familias que tienen en su seno a una persona con da\u00f1o cerebral adquirido precisan de una informaci\u00f3n, entrenamiento y adaptaci\u00f3n psicol\u00f3gica espec\u00edficas seg\u00fan los momentos del proceso\u201d. As\u00ed, distingui\u00f3 entre \u201cel diagn\u00f3stico y primeras intervenciones, la rehabilitaci\u00f3n y vuelta a casa, y la readaptaci\u00f3n y afrontamiento del futuro\u201d.<!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEl principal reto que tenemos en la atenci\u00f3n del da\u00f1o cerebral adquirido en Espa\u00f1a para los pr\u00f3ximos diez a\u00f1os es consensuar entre todos los actores implicados \u2013Administraci\u00f3n, entidades asistenciales y las personas y familias afectadas- una nueva filosof\u00eda asistencial\u201d. \u00c9ste es el horizonte presentado por Jos\u00e9 Ignacio Quemada, psiquiatra y director de la Red Menni&hellip;<\/p>\n","protected":false},"author":3,"featured_media":73371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1003,1002,2317],"tags":[3667,1005,1171,1096,1580],"class_list":["post-83520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general-en","category-noticias-en","category-publicaciones-en","tag-asistencia-en","tag-dano-cerebral-en","tag-dano-cerebral-adquirido-en","tag-dca-en","tag-modelo-de-atencion-en","category-1003","category-1002","category-2317","description-off"],"_links":{"self":[{"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/posts\/83520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/comments?post=83520"}],"version-history":[{"count":1,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/posts\/83520\/revisions"}],"predecessor-version":[{"id":83523,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/posts\/83520\/revisions\/83523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/media\/73371"}],"wp:attachment":[{"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/media?parent=83520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/categories?post=83520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/tags?post=83520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}