{"id":42281,"date":"2019-01-22T12:52:27","date_gmt":"2019-01-22T12:52:27","guid":{"rendered":"http:\/\/xn--daocerebral-2db.es\/?p=42281"},"modified":"2024-01-06T16:14:24","modified_gmt":"2024-01-06T16:14:24","slug":"los-colegios-eskibel-y-erain-traen-de-nuevo-la-alegria-de-la-tamborrada-a-nuestro-centro-en-zuatzu","status":"publish","type":"post","link":"https:\/\/xn--daocerebral-2db.es\/en\/los-colegios-eskibel-y-erain-traen-de-nuevo-la-alegria-de-la-tamborrada-a-nuestro-centro-en-zuatzu\/","title":{"rendered":"Los colegios Eskibel y Erain traen de nuevo la alegr\u00eda de la Tamborrada a nuestro centro en Zuatzu"},"content":{"rendered":"<p>Disfrutamos much\u00edsimo con los sonidos de los tambores y del entusiasmo que nos transmitieron<\/p>\n<p>Esta Tamborrada 2019\u00a0 nuevamente las personas usuarias del\u00a0<a href=\"http:\/\/da\u00f1ocerebral.es\/la-red-menni\/la-red-menni-en-el-pais-vasco\/\" target=\"_blank\" rel=\"noopener\">Centro de D\u00eda Aita Menni en el Parque Zuatzu<\/a>\u00a0han podido sentir la emoci\u00f3n de los tambores muy de cerca, gracias a la formaci\u00f3n compuesta por el alumnado de los colegios <a href=\"http:\/\/www.eskibel.com\/\" target=\"_blank\" rel=\"noopener\">Eskibel <\/a>-con el cual mantenemos <a href=\"http:\/\/xn--daocerebral-2db.es\/interesante-colaboracion-entre-el-colegio-eskibel-y-el-centro-de-dia-de-dano-cerebral-de-san-sebastian\/\" target=\"_blank\" rel=\"noopener\">una relaci\u00f3n muy especial<\/a>&#8211; y <a href=\"http:\/\/www.erain.es\/\" target=\"_blank\" rel=\"noopener\">Erain<\/a>. Por tercer a\u00f1o consecutivo, el centro vibr\u00f3 con los sonidos de los tambores y se contagi\u00f3 de la alegr\u00eda que nos transmitieron ni\u00f1as y ni\u00f1os emulando al regimiento de granaderos de Wiesbaden, con su casaca marr\u00f3n y roja con correa blanca en el pecho, sus faldas o pantalones blancos y su gorro marr\u00f3n con pomp\u00f3n rojo.<\/p>\n<p><strong><em>&#8220;\u00a1Es el tercer a\u00f1o que vienen y estamos encantados y muy agradecidos!&#8221;<\/em><\/strong>, nos cuenta <strong>Leire Zelaia<\/strong>, terapeuta ocupacional de nuestro equipo. De camino al Centro y como novedad este a\u00f1o, la formaci\u00f3n de los colegios Eskibel y Erain desfil\u00f3 por primera vez por el pol\u00edgono empresarial\u00a0de Zuatzu ante la sorpresa de muchos profesionales que se asomaron a las ventanas para ver a ni\u00f1as y ni\u00f1os por sus calles. As\u00ed reflejaba Diario Vasco la noticia.<\/p>\n<p><a href=\"http:\/\/tamborrada.diariovasco.com\/tamborrada-zuatzu-20190118133833-nt.html\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-42274 size-full\" src=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/01\/Tamborrada-Eskibel-Diario-Vasco.jpg\" alt=\"Tamborrada Eskibel Diario Vasco\" width=\"600\" height=\"505\" srcset=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/01\/Tamborrada-Eskibel-Diario-Vasco.jpg 600w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2019\/01\/Tamborrada-Eskibel-Diario-Vasco-300x252.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>En el v\u00eddeo podemos ver a cantineras, gastadores, barriles y tambores, con Ignacio de Loyola Cardarelli como abanderado y Sof\u00eda Agut Marquet de tambor mayor. Con esta tamborrada txiki, ya casi tradicional en nuestro centro, desde el pasado viernes 18 comenzamos a celebrar San Sebasti\u00e1n. Eskerrik asko! Un placer recibiros de nuevo, siempre es muy emocionante. \u00a1Gracias por venir!<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/Ql5I9rVi55s\" width=\"100%\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Disfrutamos much\u00edsimo con los sonidos de los tambores y del entusiasmo que nos transmitieron Esta Tamborrada 2019\u00a0 nuevamente las personas usuarias del\u00a0Centro de D\u00eda Aita Menni en el Parque Zuatzu\u00a0han podido sentir la emoci\u00f3n de los tambores muy de cerca, gracias a la formaci\u00f3n compuesta por el alumnado de los colegios Eskibel -con el cual&hellip;<\/p>\n","protected":false},"author":3,"featured_media":74097,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1004,1036,1003,1002],"tags":[],"class_list":["post-42281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-en","category-destacados-en","category-general-en","category-noticias-en","category-1004","category-1036","category-1003","category-1002","description-off"],"_links":{"self":[{"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/posts\/42281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/comments?post=42281"}],"version-history":[{"count":1,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/posts\/42281\/revisions"}],"predecessor-version":[{"id":79891,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/posts\/42281\/revisions\/79891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/media\/74097"}],"wp:attachment":[{"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/media?parent=42281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/categories?post=42281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/tags?post=42281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}