{"id":38921,"date":"2018-09-05T07:23:52","date_gmt":"2018-09-05T07:23:52","guid":{"rendered":"http:\/\/xn--daocerebral-2db.es\/?p=38921"},"modified":"2024-01-06T17:22:15","modified_gmt":"2024-01-06T17:22:15","slug":"espero-aportar-a-los-nuevos-logopedas-una-vision-clinica-y-sobre-todo-el-amor-a-esta-profesion","status":"publish","type":"post","link":"https:\/\/xn--daocerebral-2db.es\/en\/espero-aportar-a-los-nuevos-logopedas-una-vision-clinica-y-sobre-todo-el-amor-a-esta-profesion\/","title":{"rendered":"&#8220;Espero aportar a los nuevos logopedas una visi\u00f3n cl\u00ednica y, sobre todo, el amor a esta profesi\u00f3n&#8221;"},"content":{"rendered":"<p>La logopeda Patricia Murciego Rubio, que desarrolla su trabajo en la Unidad de Da\u00f1o Cerebral del Centro Hospitalario Benito Menni de Valladolid, a\u00a0partir de ahora ejercer\u00e1 tambi\u00e9n como profesora asociada de la <a href=\"http:\/\/www.uva.es\/export\/sites\/uva\/\" target=\"_blank\" rel=\"noopener\">Universidad de Valladolid<\/a><\/p>\n<h4><span style=\"color: #666e74;\">&#8220;No podemos ser buenos profesionales si s\u00f3lo nos centramos en la pr\u00e1ctica o en la teor\u00eda, las dos deben convivir para enriquecer y mejorar los tratamientos de los pacientes&#8221;, declara.\u00a0 Aunque nuestra compa\u00f1era es habitual en las p\u00e1ginas de la Red Menni, vamos a aprovechar esta noticia para conocerla mejor.<\/span><\/h4>\n<h4><\/h4>\n<h4><strong>Sabemos que eres logopeda y que tu formaci\u00f3n es extensa,\u00a0\u00bfcu\u00e1l es concretamente?<\/strong><\/h4>\n<p>Soy diplomada y graduada por la Universidad de Valladolid. Al terminar la diplomatura realic\u00e9 en la Universidad Pontificia de Salamanca\u00a0el <strong>\u2018Experto en Terapia Orofacial y Miofuncional\u2019<\/strong>. Por la necesidad de conocer m\u00e1s a fondo la patolog\u00eda infantil, curs\u00e9 un <strong>m\u00e1ster en atenci\u00f3n temprana<\/strong>. A\u00f1os despu\u00e9s me he animado a comenzar mi andadura investigadora y estudi\u00e9 en la Universidad de Le\u00f3n un <strong>m\u00e1ster en &#8216;Investigaci\u00f3n en ciencias sociosanitarias&#8217;<\/strong> e<strong> inici\u00e9 mi tesis doctoral en la Facultad de Medicina de la Universidad de Valladolid, la cual estoy realizando en el momento actual. Adem\u00e1s he cursado multitud de cursos sobre patolog\u00eda neurol\u00f3gica<\/strong>, pero no son formaci\u00f3n reglada como la formaci\u00f3n anterior, aunque permiten mejorar mi especializaci\u00f3n y tratamiento hacia los pacientes.<\/p>\n<h4>\u00a0<strong>\u00bfCu\u00e1nto tiempo llevas trabajando en la Unidad de Da\u00f1o Cerebral de Hermanas Hospitalarias en Valladolid?<\/strong><\/h4>\n<p>Comenc\u00e9 en el a\u00f1o 2008, al terminar mis estudios particip\u00e9 con una beca en el centro y al terminar la misma me qued\u00e9, <strong>este a\u00f1o cumplo 10 a\u00f1os como colaboradora de la Red Menni de Da\u00f1o Cerebral<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-38917\" src=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2018\/09\/Terapia-orofacial.jpg\" alt=\"Terapia-orofacial\" width=\"400\" height=\"533\" srcset=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2018\/09\/Terapia-orofacial.jpg 400w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2018\/09\/Terapia-orofacial-225x300.jpg 225w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<h4><strong>\u00bfPodr\u00edas describirnos un poco tu trabajo dentro de la Unidad?<\/strong><\/h4>\n<p>Mis funciones dentro del equipo son <strong>evaluar y rehabilitar tanto a ni\u00f1os y ni\u00f1as como a personas adultas las <a href=\"http:\/\/da\u00f1ocerebral.es\/el-dano-cerebral\/consecuencias\/\" target=\"_blank\" rel=\"noopener\">dificultades provocadas por el da\u00f1o cerebral <\/a>en el \u00e1mbito de la comunicaci\u00f3n y alimentaci\u00f3n<\/strong>.<\/p>\n<h4><strong>\u00bfCu\u00e1les son las secuelas del DCA en cuya rehabilitaci\u00f3n es m\u00e1s necesaria la atenci\u00f3n logop\u00e9dica? <\/strong><\/h4>\n<p>El da\u00f1o cerebral puede provocar alteraciones en el habla, en la voz, en la audici\u00f3n, en la degluci\u00f3n o en el lenguaje, tanto a nivel oral como escrito, tanto comprensivo como expresivo, pero el porcentaje mayor se sit\u00faa en los trastornos del lenguaje y las <a href=\"http:\/\/xn--daocerebral-2db.es\/publicacion\/guia-para-el-manejo-de-la-disfagia-pautas-para-personas-con-problemas-de-deglucion\/\" target=\"_blank\" rel=\"noopener\">dificultades deglutorias<\/a>. Estas \u00faltimas, adem\u00e1s de por el elevado porcentaje de pacientes a las que afectan, son importantes por la gravedad, ya que es un valor pron\u00f3stico negativo. <strong>Cuando una persona con da\u00f1o cerebral presenta disfagia puede producir otras alteraciones si esta no es correctamente tratada, como problemas respiratorios o incluso paradas cardiorrespiratorias por atragantamiento<\/strong> y empeorar el cuadro inicial.<\/p>\n<h4><strong>\u00bfC\u00f3mo se lleva a cabo en el Centro Hospitalario Benito Menni y, por extensi\u00f3n, en los equipos de la Red Menni?<\/strong><\/h4>\n<p>Todos los centros intentamos trabajar de forma coordinada, siguiendo una din\u00e1mica de trabajo similar. <strong>Las sesiones de tratamiento de los pacientes se realizan de forma individual, aunque existen talleres grupales con objetivos muy espec\u00edficos. Todos los pacientes reciben una evaluaci\u00f3n multidisciplinar, coordinada por la persona responsable, y tras ella el equipo marca los objetivos terap\u00e9uticos<\/strong>, reevaluando cada 3 meses las modificaciones en los mismos o el alta del paciente si se han cumplido.<\/p>\n<h4><strong>Dentro de todo este abanico de secuelas, la disfagia ocupa un lugar importante, \u00bfcu\u00e1ndo o en qu\u00e9 tipo de pacientes es m\u00e1s frecuente? <\/strong><\/h4>\n<p>Como dec\u00eda, <strong>dentro de las secuelas que provoca el da\u00f1o cerebral<\/strong>, la <a href=\"http:\/\/xn--daocerebral-2db.es\/avances-e-innovacion-en-el-tratamiento-de-la-disfagia\/\" target=\"_blank\" rel=\"noopener\">disfagia<\/a> tiene gran relevancia, tanto por su gravedad como por los porcentajes de pacientes que la presentan. Existen multitud de estudios al respecto que dan porcentajes dispares, pero en una parte de mi tesis doctoral se analiza este dato y <strong>el porcentaje aproximado es de un 40%, siendo el s\u00edntoma de mayor relevancia dentro del \u00e1mbito logop\u00e9dico<\/strong>.<\/p>\n<h4><strong>\u00bfEl abordaje de las dificultades de la degluci\u00f3n sigue siendo una de las asignaturas pendientes? Si es as\u00ed, \u00bfen qu\u00e9 \u00e1mbitos es m\u00e1s necesario formar a los equipos profesionales en su manejo?<\/strong><\/h4>\n<p><strong>Por desgracia, sigue siendo un s\u00edntoma muy olvidado<\/strong> en muchos centros de atenci\u00f3n al paciente con trastornos neurol\u00f3gicos. <strong>Ser\u00eda necesario formar tanto a profesionales como a familiares, todos deben conocer los s\u00edntomas que pueden hacerte sospechar de estas dificultades deglutorias y c\u00f3mo se pueden resolver; <\/strong>se desconoce la figura del logopeda y la posibilidad de recuperaci\u00f3n.<\/p>\n<h4><strong>Debido a tu predisposici\u00f3n a compartir tu conocimiento y experiencia participas como docente en distintos cursos, principalmente para logopedas. \u00bfPodr\u00edas darnos algunos ejemplos de los lugares, congresos y entidades para las que han impartido formaci\u00f3n?<\/strong><\/h4>\n<p>La formaci\u00f3n que imparto est\u00e1 relacionada con la intervenci\u00f3n logop\u00e9dica en el da\u00f1o cerebral, tanto infantil como adulto, aunque <strong>mi mayor experiencia y formaci\u00f3n est\u00e1 encaminada a los trastornos deglutorios<\/strong>. <strong>Participo en la <a href=\"http:\/\/www.santpau.cat\/es\/web\/public\/escola-de-patologia-del-llenguatge\" target=\"_blank\" rel=\"noopener\">Escuela de Patolog\u00eda del Lenguaje del Hospital Santa Creu y San Pau <\/a>de Barcelona<\/strong>, en el m\u00e1ster de disfagia, un centro de reconocido prestigio tanto a nivel nacional como internacional. <strong>Tambi\u00e9n colaboro con distintos colegios profesionales de logopedia, centros de formaci\u00f3n, universidades, asociaciones y sociedades m\u00e9dicas<\/strong>, dando cursos a personal sanitario o familiares sobre el manejo de estos trastornos.<\/p>\n<h4><strong>\u00bfCrees que es necesario formar en atenci\u00f3n al DCA y sus secuelas a los estudiantes de las carreras sanitarias? <\/strong><\/h4>\n<p>Existe un gran desconocimiento sobre las secuelas del da\u00f1o cerebral y sobre los profesionales que trabajamos en este campo.Todav\u00eda muchos <strong>profesionales de la medicina y la enfermer\u00eda desconocen el papel del logopeda y eso crea dificultades en la derivaci\u00f3n de estos pacientes a centros de rehabilitaci\u00f3n<\/strong>. <strong>Si en las propias facultades se conociera esta posibilidad de mejora de la calidad de vida de los pacientes, la atenci\u00f3n que se les ofrece ser\u00eda m\u00e1s adecuada.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-38919\" src=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2018\/09\/LOGOPEDA_disfagia.jpg\" alt=\"LOGOPEDA_disfagia\" width=\"600\" height=\"311\" srcset=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2018\/09\/LOGOPEDA_disfagia.jpg 600w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2018\/09\/LOGOPEDA_disfagia-300x155.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<h4><strong>\u00bfC\u00f3mo llegas a dar clases en la Universidad de Valladolid?<\/strong><\/h4>\n<p><strong>Llevo a\u00f1os colaborando con la Universidad como tutora de pr\u00e1cticas y en distintas charlas y cursos para estudiantes y profesionales<\/strong>, pero en <strong>este curso voy a comenzar como profesora asociada, un reto<\/strong> porque habitualmente la formaci\u00f3n que imparto es a profesionales.<\/p>\n<h4><strong>\u00bfEn el Grado de Logopedia?<\/strong><\/h4>\n<p>S\u00ed, que se sit\u00faa en la Facultad de Medicina, en el edificio de Ciencias de la Salud, junto con Medicina, Enfermer\u00eda y Nutrici\u00f3n humana y diet\u00e9tica.<\/p>\n<h4><strong>\u00bfCrees que es interesante\u00a0compaginar la labor docente el trabajo cl\u00ednico?<\/strong><\/h4>\n<p><strong>Creo que es vital darle a la parte cl\u00ednica el aporte de docencia y a la parte docente la parte cl\u00ednica.<\/strong> Los alumnos deben aprender de la experiencia profesional pero no podemos olvidar la importancia del marco te\u00f3rico en cualquier profesi\u00f3n, <strong>no podemos ser buenos profesionales si s\u00f3lo nos centramos en la pr\u00e1ctica o en la teor\u00eda, las dos deben convivir para enriquecer y mejorar los tratamientos de los pacientes.<\/strong><\/p>\n<h4><strong>Gracias a esta experiencia, \u00bfc\u00f3mo crees que puede enriquecerse tu trabajo en el Centro Hospitalario Benito Menni?<\/strong><\/h4>\n<p><strong>Ense\u00f1ar es un aprendizaje constante, te permite no s\u00f3lo actualizarte constantemente sino tambi\u00e9n replantearte tu parte cl\u00ednica, mejorando la teor\u00eda que da base a los tratamientos.<\/strong><\/p>\n<h4>\u00a0<strong>\u00bfY cu\u00e1l crees que puede ser tu mayor aportaci\u00f3n en la Universidad?<\/strong><\/h4>\n<p><strong>La de una logopeda que ense\u00f1a a otros logopedas.<\/strong> Hace tiempo se realiz\u00f3 en las redes sociales una campa\u00f1a para subrayar la importancia de que los profesionales de la logopedia ense\u00f1en a otros futuros profesionales, aportando la visi\u00f3n cl\u00ednica. Hasta el momento actual muchos de los profesores no eran logopedas, proven\u00edan de otras \u00e1reas de conocimiento, y en algunos casos es importante pero en otros casos la falta de pr\u00e1ctica cl\u00ednica deja el aprendizaje sesgado, sin una visi\u00f3n real. <strong>Creo que a\u00fan me queda much\u00edsimo por aprender, pero de mi peque\u00f1a experiencia espero dotar a los nuevos logopedas de una visi\u00f3n cl\u00ednica y sobre todo del amor a esta profesi\u00f3n, que puede ayudar tanto a muchas personas con graves dificultades.<\/strong><\/p>\n<h4><span style=\"color: #666e74;\">Sin duda Patricia conseguir\u00e1 transmitir a su alumnado su experiencia cl\u00ednica como logopeda en nuestra Unidad de DCA en Valladolid, su conocimiento y su gran amor por la profesi\u00f3n. Desde aqu\u00ed le deseamos toda la suerte del mundo en esta nueva etapa.<br \/>\n<\/span><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La logopeda Patricia Murciego Rubio, que desarrolla su trabajo en la Unidad de Da\u00f1o Cerebral del Centro Hospitalario Benito Menni de Valladolid, a\u00a0partir de ahora ejercer\u00e1 tambi\u00e9n como profesora asociada de la Universidad de Valladolid &#8220;No podemos ser buenos profesionales si s\u00f3lo nos centramos en la pr\u00e1ctica o en la teor\u00eda, las dos deben convivir&hellip;<\/p>\n","protected":false},"author":3,"featured_media":73749,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1004,1036,1003],"tags":[2491,1101],"class_list":["post-38921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-en","category-destacados-en","category-general-en","tag-experiencia-clinica-en","tag-formacion-en","category-1004","category-1036","category-1003","description-off"],"_links":{"self":[{"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/posts\/38921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/comments?post=38921"}],"version-history":[{"count":1,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/posts\/38921\/revisions"}],"predecessor-version":[{"id":80314,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/posts\/38921\/revisions\/80314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/media\/73749"}],"wp:attachment":[{"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/media?parent=38921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/categories?post=38921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/en\/wp-json\/wp\/v2\/tags?post=38921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}