{"id":75503,"date":"2023-10-18T14:38:10","date_gmt":"2023-10-18T14:38:10","guid":{"rendered":"https:\/\/xn--daocerebral-2db.es\/los-recuerdos-del-futbol-de-la-real-y-el-athletic-vuelven-a-estimular-a-personas-con-dano-cerebral\/"},"modified":"2024-01-04T12:24:53","modified_gmt":"2024-01-04T12:24:53","slug":"los-recuerdos-del-futbol-de-la-real-y-el-athletic-vuelven-a-estimular-a-personas-con-dano-cerebral","status":"publish","type":"post","link":"https:\/\/xn--daocerebral-2db.es\/ca\/los-recuerdos-del-futbol-de-la-real-y-el-athletic-vuelven-a-estimular-a-personas-con-dano-cerebral\/","title":{"rendered":"Los recuerdos del f\u00fatbol de la Real y el Athletic vuelven a estimular a personas con da\u00f1o cerebral"},"content":{"rendered":"<p>Los talleres de reminiscencia basada en el f\u00fatbol tienen como objetivo estimular y recuperar recuerdos de la infancia, juventud y madurez asociados a este deporte en personas mayores, con da\u00f1o cerebral o con enfermedad mental. Est\u00e1n organizados por la <a href=\"https:\/\/www.futbolistasfeafv.com\/\" target=\"_blank\" rel=\"noopener\">Federaci\u00f3n Espa\u00f1ola de Asociaciones de Futbolistas Veteranos<\/a> (FEAFV) y cuentan con el apoyo de la Fundaci\u00f3n LaLiga.<\/p>\n<p>Personas con\u00a0da\u00f1o cerebral, personas con\u00a0enfermedad mental y\u00a0<a href=\"https:\/\/www.aita-menni.org\/es\/que-hacemos\/persona-mayor\/\" target=\"_blank\" rel=\"noopener\">personas mayores<\/a>\u00a0de los centros de\u00a0<a href=\"https:\/\/www.aita-menni.org\/es\/quienes-somos\/\" target=\"_blank\" rel=\"noopener\">Hermanas Hospitalarias Aita Menni<\/a>\u00a0en Bizkaia y Gipuzkoa vuelven a participar en los\u00a0Talleres de Reminiscencia basada en el f\u00fatbol, que nuestra Instituci\u00f3n lleva incluyendo desde 2015 en sus programas de atenci\u00f3n.<\/p>\n<p>En concreto, desde inicios de octubre de este a\u00f1o ya se est\u00e1n realizando talleres en el\u00a0<a href=\"https:\/\/da\u00f1ocerebral.es\/la-red-menni\/la-red-menni-en-el-pais-vasco\/\" target=\"_blank\" rel=\"noopener\">Centro de D\u00eda de Da\u00f1o Cerebral Aita Menni de San Sebasti\u00e1n<\/a>\u00a0y en el Centro de D\u00eda de Da\u00f1o Cerebral y Hospital de D\u00eda para personas con enfermedad mental de Musakola de Mondrag\u00f3n, as\u00ed como en la\u00a0<a href=\"https:\/\/www.aita-menni.org\/es\/centro\/residencia-mayores-bilbao-txurdinagabarri\/\" target=\"_blank\" rel=\"noopener\">Residencia de personas mayores Txurdinagabarri<\/a>, en Bilbao.<\/p>\n<p>La\u00a0<a href=\"https:\/\/www.laliga.com\/fundacion\" target=\"_blank\" rel=\"noopener\">Fundaci\u00f3n LaLiga<\/a>\u00a0y la\u00a0Federaci\u00f3n Espa\u00f1ola de Asociaciones de Futbolistas Veteranos\u00a0(FEAFV)\u00a0<a href=\"https:\/\/www.aita-menni.org\/es\/fundacion-laliga-feafv-taller-reminiscencia-futbol\/\" target=\"_blank\" rel=\"noopener\">firmaron el pasado mes de septiembre un acuerdo de colaboraci\u00f3n<\/a>\u00a0para impulsar el proyecto de Talleres de Reminiscencia basada en el f\u00fatbol, que lleva a cabo la FEAFV desde 2013.<\/p>\n<p>Gracias a la colaboraci\u00f3n de LaLiga, a trav\u00e9s de su Fundaci\u00f3n, durante esta temporada, se realizar\u00e1n un total de 40 talleres en residencias y centros de toda Espa\u00f1a, con el objetivo de estimular y recuperar aquellos recuerdos asociados a la infancia, juventud y madurez a trav\u00e9s del f\u00fatbol, de personas mayores, con o sin deterioro cognitivo, da\u00f1o cerebral o problemas de salud mental.<\/p>\n<p>Los talleres tienen como eje conductor la historia del f\u00fatbol e incluyen encuentros con leyendas del f\u00fatbol vasco, asistencia a entrenamientos de diversos equipos y visitas a los estadios y sus museos de la mano de los miembros de las asociaciones de futbolistas veteranos de los clubes.<\/p>\n<div id=\"attachment_67010\" style=\"width: 610px\" class=\"wp-caption alignright\"><a href=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2023\/10\/Talleres-de-reminiscencia-copia.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-67010\" class=\"wp-image-67010 size-full\" src=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2023\/10\/Talleres-de-reminiscencia-copia.jpg\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2023\/10\/Talleres-de-reminiscencia-copia.jpg 600w, https:\/\/xn--daocerebral-2db.es\/wp-content\/uploads\/2023\/10\/Talleres-de-reminiscencia-copia-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><p id=\"caption-attachment-67010\" class=\"wp-caption-text\">Con Michel Loinaz y\u00a0Alberto \u2018Bixio\u2019 Gorriz<\/p><\/div>\n<p>Entre las leyendas del balompi\u00e9 vasco que ha participado en estos talleres de reminiscencia, se pueden citar, por parte del Athletic Club, a\u00a0<strong>Fidel Uriarte, Jos\u00e9 \u00c1. Iribar, \u00c1ngel Sertutxa, Carmelo Cedr\u00fan, Daniel Ruiz Baz\u00e1n, Javier Clemente, Andoni Goikoetxea, Javier \u00abJabo\u00bb Irureta, Rafa Alkorta, Patxi Ferreira, Oskar Tabuenca, Javi Gonz\u00e1lez, Andoni Ayarza, Aitziber Juaristi \u00abTzibi\u00bb,<\/strong>\u00a0y el propio presidente de la FEAFV\u00a0<strong>Juan Mar\u00eda Zorriqueta<\/strong>.<\/p>\n<p>Por parte de la Real Sociedad, los jugadores veteranos han sido\u00a0<strong>Santi Idigoras, Javi de Pedro, Jes\u00fas Mari Satrustegi, Roberto L\u00f3pez Ufarte, Jes\u00fas Mari Zamora, Luis Miguel Arconada, Salva Iriarte, Jokin Ur\u00eda, Alberto \u00abBixio\u00bb Gorriz, Agust\u00edn Gajate, Mitxel Loinaz, Agust\u00edn Aranzabal<\/strong>\u00a0y hasta el actual presidente de la Real, J<strong>okin Aperribay<\/strong>.<\/p>\n<p>En la din\u00e1mica de los talleres se llevan a cabo actividades y juegos con v\u00eddeos y fotograf\u00edas que inciden positivamente en el trabajo de la memoria a corto y largo plazo. Tambi\u00e9n se completa un \u2018libro de vida\u2019 interactivo, que las personas participantes han de completar con relatos e im\u00e1genes de su propia historia de vida.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los talleres de reminiscencia basada en el f\u00fatbol tienen como objetivo estimular y recuperar recuerdos de la infancia, juventud y madurez asociados a este deporte en personas mayores, con da\u00f1o cerebral o con enfermedad mental. Est\u00e1n organizados por la Federaci\u00f3n Espa\u00f1ola de Asociaciones de Futbolistas Veteranos (FEAFV) y cuentan con el apoyo de la Fundaci\u00f3n LaLiga.<\/p>\n","protected":false},"author":3,"featured_media":75498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1022,1048,1021,1020],"tags":[],"class_list":["post-75503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-ca","category-destacados-ca","category-general-ca","category-noticias-ca","category-1022","category-1048","category-1021","category-1020","description-off"],"_links":{"self":[{"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/posts\/75503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/comments?post=75503"}],"version-history":[{"count":1,"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/posts\/75503\/revisions"}],"predecessor-version":[{"id":75505,"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/posts\/75503\/revisions\/75505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/media\/75498"}],"wp:attachment":[{"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/media?parent=75503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/categories?post=75503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/tags?post=75503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}