{"id":23427,"date":"2015-06-23T07:33:41","date_gmt":"2015-06-22T21:14:49","guid":{"rendered":"http:\/\/xn--daocerebral-2db.es\/?p=23427"},"modified":"2024-01-07T16:33:30","modified_gmt":"2024-01-07T16:33:30","slug":"abordaje-de-las-dificultades-cognitivas-tras-un-dano-cerebral","status":"publish","type":"post","link":"https:\/\/xn--daocerebral-2db.es\/ca\/abordaje-de-las-dificultades-cognitivas-tras-un-dano-cerebral\/","title":{"rendered":"Abordaje de las dificultades cognitivas tras un da\u00f1o cerebral"},"content":{"rendered":"<p>El\u00a0<a href=\"http:\/\/xn--daocerebral-2db.es\/el-dano-cerebral\/la-lesion-cerebral-y-sus-causas\/\">da\u00f1o cerebral adquirido<\/a>\u00a0es una realidad que afecta a toda la organizaci\u00f3n familiar, que requiere la adaptaci\u00f3n de todos sus integrantes y, a menudo, la reorganizaci\u00f3n de algunos roles.<\/p>\n<p>Las\u00a0<strong>alteraciones cognitivas tras un da\u00f1o cerebral y su rehabilitaci\u00f3n<\/strong>\u00a0centraron la sesi\u00f3n ofrecida por\u00a0<strong>Alba G\u00f3mez V\u00e9lez<\/strong>\u00a0dentro del \u00faltimo\u00a0<strong>ciclo de ayuda a las familias de personas con discapacidad neurol\u00f3gica<\/strong>\u00a0organizado por el\u00a0<a href=\"http:\/\/xn--daocerebral-2db.es\/la-red-menni\/la-red-menni-en-el-pais-vasco\/\">Centro de Neurorrehabilitaci\u00f3n Aita Menni de Bilbao<\/a>. La joven neuropsic\u00f3loga habl\u00f3 de la\u00a0<strong>implicaci\u00f3n de la familia en el proceso rehabilitador<\/strong>, importante hasta el punto de convertirse en uno de los factores de pron\u00f3stico. En este trayecto, tambi\u00e9n es fundamental no sobreproteger a la persona afectada, sino procurar, de la mano de los terapeutas, que se exponga gradualmente a retos y responsabilidades.<\/p>\n<p><strong>Son muchas las alteraciones que pueden producirse tras un da\u00f1o cerebral: motoras, sensoriales, cognitivas, de conducta y en el \u00e1mbito de la comunicaci\u00f3n<\/strong>. Todas estas\u00a0<a href=\"http:\/\/xn--daocerebral-2db.es\/el-dano-cerebral\/consecuencias\/\">secuelas<\/a>\u00a0<strong>repercuten en la funcionalidad<\/strong>\u00a0de la persona afectada. Debemos identificar en un primer momento aquellas que suponen un mayor impacto en la vida del afectado, para trabajar sobre ellas desde momentos iniciales.<\/p>\n<p>Podemos encontrar alteraciones en las <strong>diferentes funciones cognitivas<\/strong>: dificultades en la orientaci\u00f3n, atenci\u00f3n, memoria, percepci\u00f3n, razonamiento, resoluci\u00f3n de problemas, habilidades visoespaciales, c\u00e1lculo, cognici\u00f3n social, etc.<\/p>\n<p>Para intervenir sobre ellas existen tres <strong>estrategias de rehabilitaci\u00f3n neuropsicol\u00f3gica<\/strong>: la <strong>restauraci\u00f3n<\/strong> de la funci\u00f3n (recuperaci\u00f3n de la funci\u00f3n afectada a trav\u00e9s de la pr\u00e1ctica repetida), <strong>sustituci\u00f3n<\/strong> de la funci\u00f3n (mejorar esa capacidad alterada a trav\u00e9s de otras funciones preservadas) y <strong>compensaci\u00f3n<\/strong> de la funci\u00f3n (utilizaci\u00f3n de estrategias alternativas o ayudas externas).<\/p>\n<p><strong>El uso de una u otra estrategia depender\u00e1 del tipo de lesi\u00f3n, tiempo transcurrido y gravedad de la misma<\/strong>, aunque no son incompatibles y en ocasiones podremos beneficiarnos de varias de ellas. Por ejemplo, si la lesi\u00f3n es muy reciente, y la persona tiene dificultades para mantenerse concentrado en la actividad a realizar, trabajaremos con tareas de restauraci\u00f3n (ejercicios repetidos de papel y l\u00e1piz, ordenador, juegos, etc.); sin embargo, si nos encontramos con un paciente con una severa dificultad de memoria, las estrategias m\u00e1s eficaces ser\u00e1n aquellas que compensen dicha dificultad (ayudas externas como avisadores, agenda, m\u00f3vil, calendario, etc.).<\/p>\n<p>Para la puesta en marcha y el mantenimiento de las mismas es fundamental contar con el apoyo de familiares y cuidadores, que muchas veces realizan la labor de coterapeutas en el propio ambiente del paciente. Por \u00faltimo, y al tratarse de un proceso rehabilitador de largo recorrido, Alba G\u00f3mez insisti\u00f3 en que no debemos olvidar favorecer el conveniente cuidado de familiares y cuidadores.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El\u00a0da\u00f1o cerebral adquirido\u00a0es una realidad que afecta a toda la organizaci\u00f3n familiar, que requiere la adaptaci\u00f3n de todos sus integrantes y, a menudo, la reorganizaci\u00f3n de algunos roles. Las\u00a0alteraciones cognitivas tras un da\u00f1o cerebral y su rehabilitaci\u00f3n\u00a0centraron la sesi\u00f3n ofrecida por\u00a0Alba G\u00f3mez V\u00e9lez\u00a0dentro del \u00faltimo\u00a0ciclo de ayuda a las familias de personas con discapacidad neurol\u00f3gica\u00a0organizado&hellip;<\/p>\n","protected":false},"author":3,"featured_media":71749,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1022,1048,1021,1020],"tags":[1023,2287,3192],"class_list":["post-23427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-ca","category-destacados-ca","category-general-ca","category-noticias-ca","tag-dano-cerebral-ca","tag-dificultades-cognitivas-ca","tag-rehabilitacion-neuropsicologica-ca","category-1022","category-1048","category-1021","category-1020","description-off"],"_links":{"self":[{"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/posts\/23427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/comments?post=23427"}],"version-history":[{"count":1,"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/posts\/23427\/revisions"}],"predecessor-version":[{"id":82356,"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/posts\/23427\/revisions\/82356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/media\/71749"}],"wp:attachment":[{"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/media?parent=23427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/categories?post=23427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xn--daocerebral-2db.es\/ca\/wp-json\/wp\/v2\/tags?post=23427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}